{"id":19369,"date":"2018-10-11T11:32:36","date_gmt":"2018-10-11T09:32:36","guid":{"rendered":"https:\/\/www.amis-tico.eu\/de\/?p=19369"},"modified":"2020-01-08T14:51:12","modified_gmt":"2020-01-08T13:51:12","slug":"luciole","status":"publish","type":"post","link":"https:\/\/www.amis-tico.eu\/de\/2018\/luciole\/","title":{"rendered":"Luciole"},"content":{"rendered":"<p>Name<strong>: Luciole<\/strong><br \/>\ngeb.:<br \/>\nGeschlecht: weiblich<\/p>\n<p><!--more--><\/p>\n<p><strong>Patin: Regina Vogler<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19370 alignnone\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-1-300x400.jpg\" alt=\"\" width=\"263\" height=\"351\" srcset=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-1-300x400.jpg 300w, https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-1.jpg 568w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/p>\n<p>&#8222;Da ich einen Tumor entfernt bekam, muss ich im Moment eine Halskrause tragen. Da k\u00f6nnt ihr gar nicht richtig sehen, wie h\u00fcbsch ich bin.\u00a0Aber das besteist,\u00a0 ich bin sehr lieb und total verschmust.\u00a0Also, wenn du jemanden zum Kuscheln suchst, bin ich genau die Richtige. Melde dich einfach und besuche mich.\u00a0\u00dcbrigens, der Tumor war gutartig und der Kragen kommt auch bald weg.&#8220;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19371\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-2-300x400.jpg\" alt=\"\" width=\"156\" height=\"208\" srcset=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-2-300x400.jpg 300w, https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-1-2.jpg 532w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/p>\n<p><strong>Update, 26.11.2018<\/strong><\/p>\n<p>Luciole hat eine Schilddr\u00fcsenerkrankung und ben\u00f6tigt zweimal t\u00e4glich Tabletten. Leider wurde auch eine Niereninsuffizienz festgestellt. Sie bekommt Spezialfutter und Medikamente, die sie anstandslos nimmt.<br \/>\nSie ist mittlerweile d\u00fcnn geworden und auch ihr Fell ben\u00f6tigt dringend Pflege.<br \/>\nAber am meisten ben\u00f6tigt Luciole endlich ein Zuhause in dem man sich liebevoll um sie k\u00fcmmert.<\/p>\n\n\t\t\t<div id='19369-1' class='gallery gallery-19369 gallery-columns-3 gallery-size-thumbnail' itemscope itemtype='http:\/\/schema.org\/ImageGallery'>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-1-533x400.jpg' title='upd. Luciole (1)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-1-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-2-533x400.jpg' title='upd. Luciole (2)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-2-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-3-533x400.jpg' title='upd. Luciole (3)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-3-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-4-300x400.jpg' title='upd. Luciole (4)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/upd.-Luciole-4-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t\t<\/div><!-- .gallery -->\n\n<p><strong>Update, 05.03.2019 Spendenaufruf:<\/strong><\/p>\n<p>Luciole durfte Mitte Dezember auf eine Pflegestelle ziehen. Sie ist eine ganz s\u00fc\u00dfe Maus, die aber leider ihr neues Leben (noch) nicht genie\u00dfen kann. Sie hat zwar schon etwas zugenommen, nur leider geh\u00f6rt sie zu den Katzen, welche die Schilddr\u00fcsenmedikamente nicht vertragen und wo die Medikamente auch nicht richtig wirken. Sie wechselt zwischen Schilddr\u00fcsen\u00fcberfunktion und Schilddr\u00fcsenunterfunktion hin und her. Die Krankheit beeintr\u00e4chtigt sie sehr. Sie befindet sich die meiste Zeit in einer Art Ausnahmezustand, weil ihr K\u00f6rper auf Hochtouren l\u00e4uft. Sie kann schlecht entspannen, ist \u00e4ngstlich und manchmal aggressiv und sie frisst inzwischen sehr schlecht, weil ihr von den Medikamenten \u00fcbel ist. Auch ihr Fell wird immer d\u00fcnner. An den, leider seltenen,\u00a0 guten Tagen ist sie ein richtiger Engel. Die einzige Therapie, die ihr helfen kann ist eine Radiojodtherapie. Diese wird nur an wenigen Kliniken durchgef\u00fchrt und kostet \u00fcber \u20ac 2000,-. F\u00fcr uns als kleiner Verein nicht bezahlbar. Auch jetzt schon belaufen sich die Tierarztkosten auf \u00fcber \u20ac 700,-.<br \/>\nWir sind daher dringend auf Ihre Spenden angewiesen, damit wir Lucille schnell helfen k\u00f6nnen und es ihr bald wieder richtig gut geht\u2026<\/p>\n<p><a href=\"https:\/\/www.amis-tico.eu\/de\/2013\/bankverbindungen\/\">Spendenkonten<\/a>\u00a0(Verwendungszweck: \u201eTherapiekosten Luciole\u201c)<\/p>\n\n\t\t\t<div id='19369-2' class='gallery gallery-19369 gallery-columns-3 gallery-size-thumbnail' itemscope itemtype='http:\/\/schema.org\/ImageGallery'>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-1-225x400.jpg' title='Luciole up 2 (1)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-1-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-2-626x352.jpg' title='Luciole up 2 (2)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-2-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-3-626x352.jpg' title='Luciole up 2 (3)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-2-3-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\n\t\t\t<\/div><!-- .gallery -->\n\n<p>&nbsp;<\/p>\n<p><strong>Update, 14.06.2019<\/strong><\/p>\n<p><del>Luciole ist vermittelt.<\/del><\/p>\n<p><strong>Update, 08.07.2019<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-22902\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-2-626x370.jpg\" alt=\"\" width=\"428\" height=\"252\" srcset=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-2-626x370.jpg 626w, https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-2-624x369.jpg 624w, https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-2.jpg 700w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/p>\n<p>&#8222;Hallo, ich wollte mal berichten was in letzter Zeit so passiert ist:<\/p>\n<p>Kurz vor Weihnachten hab ich richtig Gl\u00fcck gehabt. Ich durfte auf eine Pflegestelle ziehen. So richtig gut gings mir damals nicht. Durch die Schilddr\u00fcsen\u00fcberfunktion arbeitet n\u00e4mlich alles auf Hochtouren. Das ist so, als w\u00fcrde man mit angezogener Handbremse Vollgas geben. Nicht gut f\u00fcr das System. Meine Pflegestelle hat dann entschieden, dass meine Schilddr\u00fcse mit Radio-Jod bestrahlt wird, weil die Tabletten nicht halfen. Das war richtig teuer. Aber meine Pflegestelle hat gesagt, dass ich ansonsten in den Himmel komme. Und daf\u00fcr bin ich viel zu jung\u2026 Also haben sie das alles bezahlt. Da bin ich echt dankbar. Denn nun brauch ich keine Medikamente mehr und mein Stoffwechsel normalisiert sich von Tag zu Tag mehr. Ich bin viel entspannter, lass mich inzwischen auch anfassen, mein Herzschlag ist wieder normal und die Nieren sind auch ok.<\/p>\n<p>Ich bin zwar (noch?) keine Schmusekatze, aber super neugierig, aufgeschlossen und nat\u00fcrlich wunderh\u00fcbsch! Ich erz\u00e4hle auch gerne mal was ich so erlebt hab und kann sehr fordernd gucken. So bekomm ich fast immer was ich will.<\/p>\n<p>Dann kam der Tag, an dem ich in ein neues Zuhause ziehen durfte. Eigentlich w\u00e4re alles super, aber\u2026 ich habe entschieden nur noch Trockenfutter zu fressen. Nicht toll, ich wei\u00df. Aber ich mag das andere Zeugs nicht mehr. Nur, nun muss ich oft am Tag was fressen. Denn das Trockenfutter macht nicht lange satt. Aber hier leben auch noch andere Katzen, die gesundheitliche Probleme haben und gesund ern\u00e4hrt werden. Die d\u00fcrfen nichts von meinem Futter. Also kann mein Frauchen mein Futter nicht einfach so f\u00fcr mich stehen lassen. Denn dann st\u00fcrzen sich die anderen da drauf. Ich m\u00fcsste also alle paar Stunden gef\u00fcttert werden, aber mein Frauchen ist ja auch nicht immer hier\u2026 Und ich bin auch total ger\u00e4uschempfindlich. Wenn irgendwo eine der anderen Katzen miaut oder sich was bewegt, h\u00f6re ich sofort auf zu fressen. Also brauch ich Ruhe beim Fressen, denn ich muss noch zunehmen\u2026 Und so richtig gl\u00fccklich bin ich mit den anderen Katzen auch nicht. Ich h\u00e4tte lieber meine Ruhe und meine Menschen f\u00fcr mich alleine\u2026<\/p>\n<p>So, suche ich also nun noch einmal meinen End-Platz. Am besten als Einzelkatze. Wichtig ist ein ruhiger Haushalt, ohne Kinder. Ich bin immer noch skeptisch was Menschen angeht und fass nicht so schnell Vertrauen. Ich mag einen geregelten Tagesablauf, Ver\u00e4nderungen sind nicht so mein Ding\u2026 Und, es zieht mich ziemlich nach drau\u00dfen. Einen gesicherten, katzengerecht ausgestatteten Balkon, den ich m\u00f6glichst auch \u00fcber eine Katzenklappe jederzeit betreten kann, oder noch besser gesicherten Freigang, das w\u00fcnsche ich mir. Gesundheitlich braucht nur alle 6 Monate der Schilddr\u00fcsenwert im Blut kontrolliert werden. Sonst muss nichts beachtet werden.<\/p>\n<p>Also, wenn Du geduldig bist und nach einer Charakterkatze Ausschau h\u00e4ltst, dann komm mich doch mal besuchen.&#8220;<\/p>\n\n\t\t\t<div id='19369-3' class='gallery gallery-19369 gallery-columns-3 gallery-size-thumbnail' itemscope itemtype='http:\/\/schema.org\/ImageGallery'>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-5-618x400.jpg' title='Luciole up 6 (5)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-5-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-4-607x400.jpg' title='Luciole up 6 (4)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-4-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-3-316x400.jpg' title='Luciole up 6 (3)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-3-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t<div class='gallery-row gallery-col-3 gallery-clear'>\n\t\t\t\t\t<figure class='gallery-item col-3' itemprop='associatedMedia' itemscope itemtype='http:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t<div class='gallery-icon landscape'><a href='https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-1-582x400.jpg' title='Luciole up 6 (1)'><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"150\" src=\"https:\/\/www.amis-tico.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/10\/Luciole-up-6-1-170x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" itemprop=\"thumbnail\" \/><\/a><\/div>\n\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t\t<\/div><!-- .gallery -->\n\n<p>&nbsp;<\/p>\n<p><strong>Update, 08.01.2020<\/strong><\/p>\n<p>Luciole ist vermittelt.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Name: Luciole geb.: Geschlecht: weiblich<\/p>\n","protected":false},"author":7,"featured_media":19372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[248],"tags":[],"class_list":["post-19369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vermittelt-2020"],"_links":{"self":[{"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/posts\/19369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/comments?post=19369"}],"version-history":[{"count":5,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/posts\/19369\/revisions"}],"predecessor-version":[{"id":25061,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/posts\/19369\/revisions\/25061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/media\/19372"}],"wp:attachment":[{"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/media?parent=19369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/categories?post=19369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amis-tico.eu\/de\/wp-json\/wp\/v2\/tags?post=19369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}